{"id":1945,"date":"2023-09-01T21:51:00","date_gmt":"2023-09-01T21:51:00","guid":{"rendered":"https:\/\/apimondia.org\/?p=1945"},"modified":"2025-12-03T22:03:21","modified_gmt":"2025-12-03T22:03:21","slug":"apimondia-2023","status":"publish","type":"post","link":"https:\/\/apimondia.org\/fra\/apimondia-2023\/","title":{"rendered":"Apimondia 2023 - 48e congr\u00e8s apicole"},"content":{"rendered":"<p class=\"has-text-align-center\"><strong>4 - 8 septembre 2023 - Santiago, Chili<\/strong><\/p>\n\n\n\n<p>Apimondia est l'organisation internationale des associations apicoles qui r\u00e9unit des scientifiques, des sp\u00e9cialistes et des apiculteurs du monde entier. En 2023, le Chili accueillera cet \u00e9v\u00e9nement international.<\/p>\n\n\n\n<p>Ce congr\u00e8s se d\u00e9roulera \u00e0 Santiago, la capitale du Chili, avec les montagnes enneig\u00e9es des Andes en toile de fond. Des visites techniques vous permettront de d\u00e9couvrir les exploitations apicoles des environs et de visiter des bodegas de renomm\u00e9e mondiale pour d\u00e9guster des vins chiliens. Pendant le congr\u00e8s Apimondia, vous pourrez rencontrer de vieux amis et vous en faire de nouveaux en visitant l'ApiEXPO et en prenant connaissance des derni\u00e8res avanc\u00e9es scientifiques et des derni\u00e8res id\u00e9es en mati\u00e8re d'apiculture.<\/p>\n\n\n\n<p>Le 48e congr\u00e8s d'Apimondia se d\u00e9roulera sur trois jours :<\/p>\n\n\n\n<p><strong>L'apiculture durable dans un monde en mutation<\/strong><br>Se concentrer sur l'apiculture durable et inclure l'acte d'\u00e9lever des abeilles en utilisant les principes de l'\u00e9cologie, o\u00f9 l'utilisation des abeilles respecte les r\u00e8gles de leur environnement. Une apiculture respectueuse de l'environnement peut \u00eatre durable et rentable, m\u00eame si le changement climatique rend l'apiculture plus difficile.<\/p>\n\n\n\n<p><strong>Produits de la ruche \u00e0 valeur ajout\u00e9e<\/strong><br>Le miel et la cire d'abeille sont les principaux produits sur lesquels s'appuient les apiculteurs. Toutefois, la propolis, le pollen, la gel\u00e9e royale, les produits corporels, le venin d'abeille et d'autres encore sont des produits pr\u00e9cieux de la ruche que les apiculteurs, petits et grands, peuvent utiliser pour accro\u00eetre les b\u00e9n\u00e9fices de l'apiculture. En outre, ces produits sont des ressources alimentaires et th\u00e9rapeutiques pr\u00e9cieuses qui contribuent aux industries alimentaires et pharmaceutiques, garantissant ainsi une meilleure sant\u00e9 humaine. Cette journ\u00e9e se concentrera sur ces \u201cproduits \u00e0 valeur ajout\u00e9e\u201d et sur la mani\u00e8re de les int\u00e9grer dans votre apiculture.<\/p>\n\n\n\n<p><strong>Utilisation des sols, biodiversit\u00e9 et apiculture<\/strong><br>Les r\u00f4les que les changements d'utilisation des sols et la biodiversit\u00e9 jouent dans la sant\u00e9 et la productivit\u00e9 des abeilles domestiques et sauvages seront discut\u00e9s. L'apiculture est tributaire d'un bon fourrage, ce qui est en partie influenc\u00e9 par l'\u00e9volution des modes d'utilisation des sols. En particulier, l'agriculture intensive, l'urbanisation et le changement climatique font qu'il est difficile de trouver de bons emplacements pour les abeilles domestiques et ont un impact sur la pollinisation sauvage.<\/p>","protected":false},"excerpt":{"rendered":"<p>Le 48e Congr\u00e8s apicole international Apimondia - 4-8 septembre 2023, Santiago, Chili - r\u00e9unira des apiculteurs, des scientifiques et des professionnels de l'industrie du monde entier pour explorer l'apiculture durable, les innovations en mati\u00e8re de produits de la ruche et la biodiversit\u00e9 sous des climats changeants.<\/p>","protected":false},"author":2,"featured_media":1222,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1945","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/apimondia.org\/fra\/wp-json\/wp\/v2\/posts\/1945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apimondia.org\/fra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apimondia.org\/fra\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apimondia.org\/fra\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/apimondia.org\/fra\/wp-json\/wp\/v2\/comments?post=1945"}],"version-history":[{"count":3,"href":"https:\/\/apimondia.org\/fra\/wp-json\/wp\/v2\/posts\/1945\/revisions"}],"predecessor-version":[{"id":1949,"href":"https:\/\/apimondia.org\/fra\/wp-json\/wp\/v2\/posts\/1945\/revisions\/1949"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apimondia.org\/fra\/wp-json\/wp\/v2\/media\/1222"}],"wp:attachment":[{"href":"https:\/\/apimondia.org\/fra\/wp-json\/wp\/v2\/media?parent=1945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apimondia.org\/fra\/wp-json\/wp\/v2\/categories?post=1945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apimondia.org\/fra\/wp-json\/wp\/v2\/tags?post=1945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}